{"id":16517,"date":"2024-09-10T13:24:49","date_gmt":"2024-09-10T13:24:49","guid":{"rendered":"https:\/\/www.marcofilicori.it\/?p=16517"},"modified":"2025-08-17T08:20:16","modified_gmt":"2025-08-17T08:20:16","slug":"inps-e-congedo-per-pma","status":"publish","type":"post","link":"https:\/\/www.marcofilicori.it\/en\/pma\/inps-e-congedo-per-pma\/","title":{"rendered":"INPS e congedo per PMA"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>Si pu\u00f2 richiedere il congedo per PMA? Come? Quanti di giorni di malattia comporta?<\/strong><br \/>\nBench\u00e9 la procreazione medicalmente assistita non rientri nei termini dell\u2019aspettativa retribuita \u00e8 possibile ottenere un periodo di assenza retribuita dal lavoro.<\/p>\n<p style=\"text-align: justify;\"><strong>Secondo l\u2019INPS<\/strong> (Messaggio n. 7412 del 4 marzo 2005), sebbene le pratiche di fecondazione assistita non siano una \u201cmalattia\u201d in senso classico possono essere a essa assimilate.<br \/>\n<strong>Occorre infatti considerare tutto il periodo di riposo prescritto alla paziente affinch\u00e9 l\u2019impianto dell\u2019embrione in utero abbia buone probabilit\u00e0 di andare a buon fine<\/strong>.<\/p>\n<p style=\"text-align: justify;\">In particolare vengono considerati:<\/p>\n<ul style=\"text-align: justify;\">\n<li>il rischio di ipercontrattilit\u00e0 del miometrio, sensibile anche a piccoli sforzi<\/li>\n<li>il livello di stress associato alle oscillazioni cicliche ormonali<\/li>\n<\/ul>\n<h3 style=\"text-align: justify;\">Quanti giorni di malattia per PMA?<\/h3>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-16316\" title=\"Medico Specialista PMA Prof. Marco Filicori - Clinica PMA Bologna\" src=\"https:\/\/www.marcofilicori.it\/wp-content\/uploads\/2024\/06\/infertilita_coppia_2-300x188.png\" alt=\"Medico Specialista PMA Prof. Marco Filicori - Clinica PMA Bologna\" width=\"480\" height=\"300\" srcset=\"https:\/\/www.marcofilicori.it\/wp-content\/uploads\/2024\/06\/infertilita_coppia_2-300x188.png 300w, https:\/\/www.marcofilicori.it\/wp-content\/uploads\/2024\/06\/infertilita_coppia_2-1024x640.png 1024w, https:\/\/www.marcofilicori.it\/wp-content\/uploads\/2024\/06\/infertilita_coppia_2-768x480.png 768w, https:\/\/www.marcofilicori.it\/wp-content\/uploads\/2024\/06\/infertilita_coppia_2-1536x960.png 1536w, https:\/\/www.marcofilicori.it\/wp-content\/uploads\/2024\/06\/infertilita_coppia_2-580x363.png 580w, https:\/\/www.marcofilicori.it\/wp-content\/uploads\/2024\/06\/infertilita_coppia_2-860x538.png 860w, https:\/\/www.marcofilicori.it\/wp-content\/uploads\/2024\/06\/infertilita_coppia_2-1160x725.png 1160w, https:\/\/www.marcofilicori.it\/wp-content\/uploads\/2024\/06\/infertilita_coppia_2.png 1600w\" sizes=\"(max-width: 480px) 100vw, 480px\" \/><\/p>\n<p style=\"text-align: justify;\"><strong>L\u2019INPS considera, ai fini dell&#8217;indennit\u00e0, le giornate di ricovero e quelle successive alla dimissione, prescritte dallo specialista e necessarie per un sicuro impianto dell\u2019embrione<\/strong>.<br \/>\nVengono quindi concessi <strong>21 giorni di malattia per la PMA<\/strong>, nello specifico: 1 settimana prima del transfer (trasferimento dell\u2019embrione nell\u2019utero) e 2 settimane dopo il transfer. I giorni di ricovero in day hospital vengono considerati giorni di malattia.<\/p>\n<p style=\"text-align: justify;\"><strong>Il periodo di malattia \u00e8 riconosciuto anche alla parte maschile della coppia nel caso in cui venga fatto ricorso a tecniche di PMA che richiedono il prelievo testicolare degli spermatozoi<\/strong>.<br \/>\nOve vengano effettuate tecniche di procreazione assistita che richiedono il prelievo degli spermatozoi dall\u2019epididimo o dal testicolo \u00e8 riconoscibile anche al lavoratore\u00a0un<strong> periodo di malattia della durata di 10 giorni<\/strong>.<\/p>\n<h3 style=\"text-align: justify;\">Come richiedere il congedo PMA?<\/h3>\n<p style=\"text-align: justify;\"><strong>Per richiedere il congedo PMA occorre rivolgersi sia alla clinica specializzata che ha eseguito tutte le tecniche di fecondazione assistita sia al proprio medico di base<\/strong>.<\/p>\n<p style=\"text-align: justify;\">La clinica fornir\u00e0 un certificato di infertilit\u00e0 e di fecondazione assistita per le <strong>giornate di ricovero in day hospital<\/strong>. Il medico curante invece fornir\u00e0 il certificato di malattia per le giornate successive alle dimissioni, nonch\u00e9 per i giorni di assenza dovuti agli esami pre-ricovero.<\/p>\n<p style=\"text-align: justify;\">Secondo la circolare INPS 7412, 4 marzo 2005 il documento verr\u00e0 redatto in triplice copia: una di queste verr\u00e0 inviata direttamente all\u2019INPS per via telematica, mentre le altre due verranno rilasciate alla paziente. Di queste due copie una potr\u00e0 essere conservata mentre l\u2019altra dovr\u00e0 essere consegnata al datore di lavoro.<br \/>\nIn realt\u00e0 non si tratta di copie identiche dello stesso documento, perch\u00e9 quello riservato all\u2019INPS deve contenere diagnosi e prognosi; al contrario di quello per il datore di lavoro, che potr\u00e0 contenere solo la parte relativa ai giorni di malattia, ossia la prognosi.<\/p>\n<p style=\"text-align: justify;\"><strong>Per cominciare un percorso di PMA occorre una guida esperta in grado si seguirti in tutte le complicate fasi della fecondazione assistita: <a title=\"Consulto per fecondazione assistita a Bologna e Verona\" href=\"https:\/\/www.marcofilicori.it\/contatti\/\">contatta il Prof. Filicori per un consulto specialistico a Bologna e Verona<\/a><\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Si pu\u00f2 richiedere il congedo per PMA? Come? Quanti di giorni di malattia comporta? Breve guida sul  congedo per la fecondazione assistita.<\/p>\n","protected":false},"author":5,"featured_media":16529,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[93],"tags":[98,97,99,92],"class_list":["post-16517","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-pma","tag-congedo-pma","tag-inps","tag-normative","tag-pma"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.marcofilicori.it\/en\/wp-json\/wp\/v2\/posts\/16517"}],"collection":[{"href":"https:\/\/www.marcofilicori.it\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.marcofilicori.it\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.marcofilicori.it\/en\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.marcofilicori.it\/en\/wp-json\/wp\/v2\/comments?post=16517"}],"version-history":[{"count":12,"href":"https:\/\/www.marcofilicori.it\/en\/wp-json\/wp\/v2\/posts\/16517\/revisions"}],"predecessor-version":[{"id":16947,"href":"https:\/\/www.marcofilicori.it\/en\/wp-json\/wp\/v2\/posts\/16517\/revisions\/16947"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.marcofilicori.it\/en\/wp-json\/wp\/v2\/media\/16529"}],"wp:attachment":[{"href":"https:\/\/www.marcofilicori.it\/en\/wp-json\/wp\/v2\/media?parent=16517"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.marcofilicori.it\/en\/wp-json\/wp\/v2\/categories?post=16517"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.marcofilicori.it\/en\/wp-json\/wp\/v2\/tags?post=16517"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}