{"id":16260,"date":"2024-05-27T08:59:27","date_gmt":"2024-05-27T08:59:27","guid":{"rendered":"https:\/\/www.marcofilicori.it\/?p=16260"},"modified":"2025-08-17T08:21:30","modified_gmt":"2025-08-17T08:21:30","slug":"isterosalpingografia-esame-tube-infertilita-femminile","status":"publish","type":"post","link":"https:\/\/www.marcofilicori.it\/en\/infertilita\/isterosalpingografia-esame-tube-infertilita-femminile\/","title":{"rendered":"Isterosalpingografia: esame delle tube per infertilit\u00e0 femminile"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>L\u2019isterosalpingografia (esame delle tube) \u00e8 uno dei principali esami diagnostici per scoprire le cause dell\u2019infertilit\u00e0 femminile. Permette di analizzare la morfologia dell\u2019utero e delle salpingi.<\/strong><\/p>\n<h3 style=\"text-align: justify;\">Preparazione alla Isterosalpingografia<\/h3>\n<p style=\"text-align: justify;\"><strong>L\u2019esame delle tube va eseguito nella prima parte del ciclo mestruale, quindi tra il 5\u00b0 e il 13\u00b0 giorno, senza perdite di sangue residue<\/strong>.<br \/>\nDurante il mese che precede l\u2019esecuzione dell\u2019esame la coppia deve sospendere i tentativi di arrivare a una gravidanza, di conseguenza occorre avere solo rapporti protetti (principalmente con il preservativo).<\/p>\n<p style=\"text-align: justify;\">Il giorno prima dell\u2019esame \u00e8 indicato assumere una pastiglia (o supposta) di Buscopan (farmaco antispastico), che dovr\u00e0 essere presa anche il giorno seguente, un\u2019ora prima dell\u2019esame.<\/p>\n<h3 style=\"text-align: justify;\">Come si svolge l\u2019esame delle tube<\/h3>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-16264 size-medium\" src=\"https:\/\/www.marcofilicori.it\/wp-content\/uploads\/2024\/05\/esame-tube-infertilita-femminile-300x200.jpeg\" alt=\"Esame delle tube per diagnosi infertilit\u00e0 femminile Bologna\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.marcofilicori.it\/wp-content\/uploads\/2024\/05\/esame-tube-infertilita-femminile-300x200.jpeg 300w, https:\/\/www.marcofilicori.it\/wp-content\/uploads\/2024\/05\/esame-tube-infertilita-femminile-1024x684.jpeg 1024w, https:\/\/www.marcofilicori.it\/wp-content\/uploads\/2024\/05\/esame-tube-infertilita-femminile-768x513.jpeg 768w, https:\/\/www.marcofilicori.it\/wp-content\/uploads\/2024\/05\/esame-tube-infertilita-femminile-1536x1026.jpeg 1536w, https:\/\/www.marcofilicori.it\/wp-content\/uploads\/2024\/05\/esame-tube-infertilita-femminile-580x387.jpeg 580w, https:\/\/www.marcofilicori.it\/wp-content\/uploads\/2024\/05\/esame-tube-infertilita-femminile-860x574.jpeg 860w, https:\/\/www.marcofilicori.it\/wp-content\/uploads\/2024\/05\/esame-tube-infertilita-femminile-1160x775.jpeg 1160w, https:\/\/www.marcofilicori.it\/wp-content\/uploads\/2024\/05\/esame-tube-infertilita-femminile.jpeg 1920w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>L\u2019esame delle tube viene effettuato senza anestesia, in regime ambulatoriale: durante lo svolgimento \u00e8 possibile che la paziente avverta una sensazione di fastidio (simile al dolore mestruale). Complessivamente, <strong>tutta la procedura diagnostica dura circa 30 minuti<\/strong>.<\/p>\n<p style=\"text-align: justify;\">La paziente viene fatta accomodare in posizione ginecologica, dopodich\u00e9 viene inserito lo speculum per mantenere aperta la cervice uterina.<\/p>\n<p style=\"text-align: justify;\">Successivamente alla disinfezione dei genitali viene introdotto nell\u2019utero un catetere sottile contenente la soluzione di contrasto iodato.<br \/>\nLa funzione del mezzo di contrasto \u00e8 rendere ben visibile la condizione dell\u2019utero e delle tube di Falloppio; gli strumenti radiografici acquisiranno quindi le immagini degli organi interessati e del movimento del liquido di contrasto.<\/p>\n<p style=\"text-align: justify;\">Dopo la rimozione del catetere viene aspirato anche il mezzo di contrasto e viene disinfettata la cavit\u00e0 del peritoneo per prevenire possibili infezioni.<br \/>\nPer lo stesso scopo viene prescritta anche una terapia antibiotica di 3 giorni, da cominciare la sera stessa dell\u2019esame.<\/p>\n<p style=\"text-align: justify;\">Si consiglia alla coppia di attendere il successivo ciclo mestruale prima di riprendere con i rapporti non protetti.<\/p>\n<p style=\"text-align: justify;\"><strong>L\u2019isterosalpingografia \u00e8 uno degli esami per l\u2019infertilit\u00e0 femminile che fanno parte del percorso della procreazione medicalmente assistita. <\/strong><br \/>\n<strong>Scegli un medico specialista che possa accompagnarti nel tuo percorso alla PMA a Bologna e Verona: <a title=\"Consulto per PMA a Bologna e Verona\" href=\"https:\/\/www.marcofilicori.it\/contatti\/\">contatta il Prof. Filicori<\/a><\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019isterosalpingografia (esame delle tube) \u00e8 uno dei principali esami diagnostici per scoprire le cause dell\u2019infertilit\u00e0 femminile. Permette di analizzare la morfologia dell\u2019utero e delle salpingi.<\/p>\n","protected":false},"author":5,"featured_media":16262,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[68],"tags":[82,83,84],"class_list":["post-16260","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-infertilita","tag-infertilita-femminile","tag-isterosalpingografia","tag-tube-di-falloppio"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.marcofilicori.it\/en\/wp-json\/wp\/v2\/posts\/16260"}],"collection":[{"href":"https:\/\/www.marcofilicori.it\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.marcofilicori.it\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.marcofilicori.it\/en\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.marcofilicori.it\/en\/wp-json\/wp\/v2\/comments?post=16260"}],"version-history":[{"count":4,"href":"https:\/\/www.marcofilicori.it\/en\/wp-json\/wp\/v2\/posts\/16260\/revisions"}],"predecessor-version":[{"id":16599,"href":"https:\/\/www.marcofilicori.it\/en\/wp-json\/wp\/v2\/posts\/16260\/revisions\/16599"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.marcofilicori.it\/en\/wp-json\/wp\/v2\/media\/16262"}],"wp:attachment":[{"href":"https:\/\/www.marcofilicori.it\/en\/wp-json\/wp\/v2\/media?parent=16260"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.marcofilicori.it\/en\/wp-json\/wp\/v2\/categories?post=16260"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.marcofilicori.it\/en\/wp-json\/wp\/v2\/tags?post=16260"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}